{"id":965,"date":"2018-06-10T20:39:19","date_gmt":"2018-06-10T19:39:19","guid":{"rendered":"http:\/\/blogue.fondationdegaspebeaubien.org\/?p=568"},"modified":"2020-01-29T08:38:50","modified_gmt":"2020-01-29T13:38:50","slug":"les-cinq-equipes-finalistes-du-defi-aquahacking-2018-sont-devoilees","status":"publish","type":"post","link":"https:\/\/www.fondationdegaspebeaubien.org\/fr\/les-cinq-equipes-finalistes-du-defi-aquahacking-2018-sont-devoilees\/","title":{"rendered":"Les cinq \u00e9quipes finalistes du d\u00e9fi Aquahacking 2018 sont d\u00e9voil\u00e9es"},"content":{"rendered":"<p>Toronto, ON, (Dimanche 10 juin 2018) \u2013 Cinq \u00e9quipes ont \u00e9t\u00e9 s\u00e9lectionn\u00e9es comme finalistes de la demi-finale du D\u00e9fi AquaHacking 2018.<\/p>\n<p>Au cours des trois derniers mois, certains des jeunes innovateurs les plus brillants de diverses universit\u00e9s du Qu\u00e9bec, de l&rsquo;Ontario et des \u00c9tats-Unis ont form\u00e9 des \u00e9quipes multidisciplinaires pour cr\u00e9er des solutions innovatrices en technologies propres afin de r\u00e9soudre certains probl\u00e8mes du bassin des Grands Lacs et du Saint-Laurent. Ces applications visent \u00e0 maintenir la sant\u00e9 du lac Ontario, de son bassin hydrographique et des communaut\u00e9s locales.<\/p>\n<p>Le 9 juin, seize \u00e9quipes se sont affront\u00e9es en demi-finale au RBC WaterPark Place \u00e0 Toronto, o\u00f9 un jury d&rsquo;experts et d&rsquo;acteurs cl\u00e9s des industries de l&rsquo;eau et de la technologie ont s\u00e9lectionn\u00e9 les cinq finalistes suivants:<\/p>\n<ul>\n<li style=\"list-style-type: none;\">\n<ul>\n<li>EGC Labs: Donn\u00e9es en temps r\u00e9el, alertes en temps r\u00e9el, apprentissage \u00e0 long terme: les laboratoires EGC peuvent aider les gouvernements \u00e0 identifier des mod\u00e8les de d\u00e9bordement des eaux us\u00e9es et m\u00eame les raisons qui les sous-tendent.<\/li>\n<li>E-nundation: Vous comptez acheter une propri\u00e9t\u00e9 pr\u00e8s d&rsquo;un plan d&rsquo;eau? Il serait judicieux de v\u00e9rifier si la r\u00e9gion a des ant\u00e9c\u00e9dents d&rsquo;inondation. De la fourniture de devis d&rsquo;assurance \u00e0 la pr\u00e9vision des inondations, E-Nundation innove dans l&rsquo;espace de gestion des risques de d\u00e9g\u00e2ts d&rsquo;eau.<\/li>\n<li>M Power Software: M Power Software r\u00e9unit l&rsquo;Internet des objets (IdO) et l&rsquo;IA pour pr\u00e9dire et mesurer le d\u00e9bordement des eaux us\u00e9es.<\/li>\n<li>SWIM: La solution de SWIM propose une d\u00e9tection des d\u00e9bordements d&rsquo;eaux us\u00e9es d\u00e9centralis\u00e9e robuste et polyvalente avec leur cam\u00e9ra infrarouge assist\u00e9e par drone.<\/li>\n<li>Water Puris: Il existe d\u00e9j\u00e0 des technologies sophistiqu\u00e9es pour d\u00e9truire les produits chimiques perturbateurs du syst\u00e8me endocrinien. Mais \u00e0 la maison? Pas n\u00e9cessairement. WaterPuris pirate votre cuvette de toilette pour d\u00e9grader ces produits en utilisant une combinaison de peroxyde d&rsquo;hydrog\u00e8ne et de lumi\u00e8re UV.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p>Chaque \u00e9quipe recevra un financement de 2 000 $ pour affiner sa solution au cours de l&rsquo;\u00e9t\u00e9 et participera \u00e0 une exp\u00e9dition de deux jours, toutes d\u00e9penses pay\u00e9es, sur le lac Ontario pour rencontrer diverses parties prenantes.<\/p>\n<p>Enfin, les \u00e9quipes s&rsquo;affronteront lors de la finale du D\u00e9fi AquaHacking le 25 octobre, dans le cadre de la Semaine de l&rsquo;innovation en eau de l&rsquo;Ontario (ONWin), qui se tiendra au Design Exchange de Toronto. Les \u00e9quipes recevront jusqu&rsquo;\u00e0 25 000 $ pour d\u00e9velopper et commercialiser leur solution.<\/p>\n<p>Le D\u00e9fi AquaHacking ne serait pas possible sans le g\u00e9n\u00e9reux soutien de ses principaux commanditaires, soit la Fondation de Gasp\u00e9 Beaubien, IBM Canada, la Fondation RBC, GHD, Keurig, Ovivo, Sanexen, la Ville de Montr\u00e9al, la Ville de Toronto, EY, Ontario Power Generation et de nombreux autres partenaires.<\/p>\n<p><strong>\u00c0 propos de la Fondation de Gasp\u00e9 Beaubien et Aqua Forum<\/strong><\/p>\n<p>Fond\u00e9e en 1990, la Fondation de Gasp\u00e9 Beaubien est une organisation philanthropique familiale vou\u00e9e \u00e0 la conservation de l&rsquo;eau et au soutien des entreprises familiales. La Fondation utilise une approche connue sous le nom de philanthropie entrepreneuriale dans son but d&rsquo;aider les individus, les entreprises familiales et les organisations \u00e0 devenir des agents responsables du changement positif et durable au sein de leurs communaut\u00e9s.<br \/>\nLa Fondation de Gasp\u00e9 Beaubien est \u00e0 l\u2019origine d\u2019Aqua Forum, qui est \u00e9galement soutenu par plusieurs organisations partenaires. Aqua Forum g\u00e8re le D\u00e9fi AquaHacking et d\u00e9veloppe pr\u00e9sentement un nouveau programme qui positionnera les enjeux de l\u2019eau comme enjeux de sant\u00e9 publique afin de sensibiliser la population et inciter de nouvelles actions en ce qui a trait aux efforts d\u2019am\u00e9lioration de la qualit\u00e9 de l\u2019eau en Am\u00e9rique du Nord.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Toronto, ON, (Dimanche 10 juin 2018) \u2013 Cinq \u00e9quipes ont \u00e9t\u00e9 s\u00e9lectionn\u00e9es comme finalistes de la demi-finale du D\u00e9fi AquaHacking 2018. Au cours des trois derniers mois, certains des jeunes innovateurs les plus brillants de diverses universit\u00e9s du Qu\u00e9bec, de l&rsquo;Ontario et des \u00c9tats-Unis ont form\u00e9 des \u00e9quipes multidisciplinaires pour cr\u00e9er des solutions innovatrices en [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1077,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[112],"tags":[],"class_list":["post-965","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aquaaction"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Les cinq \u00e9quipes finalistes du d\u00e9fi Aquahacking 2018 sont d\u00e9voil\u00e9es - Fondation de Gasp\u00e9 Beaubien<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fondationdegaspebeaubien.org\/fr\/les-cinq-equipes-finalistes-du-defi-aquahacking-2018-sont-devoilees\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les cinq \u00e9quipes finalistes du d\u00e9fi Aquahacking 2018 sont d\u00e9voil\u00e9es - Fondation de Gasp\u00e9 Beaubien\" \/>\n<meta property=\"og:description\" content=\"Toronto, ON, (Dimanche 10 juin 2018) \u2013 Cinq \u00e9quipes ont \u00e9t\u00e9 s\u00e9lectionn\u00e9es comme finalistes de la demi-finale du D\u00e9fi AquaHacking 2018. Au cours des trois derniers mois, certains des jeunes innovateurs les plus brillants de diverses universit\u00e9s du Qu\u00e9bec, de l&rsquo;Ontario et des \u00c9tats-Unis ont form\u00e9 des \u00e9quipes multidisciplinaires pour cr\u00e9er des solutions innovatrices en [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fondationdegaspebeaubien.org\/fr\/les-cinq-equipes-finalistes-du-defi-aquahacking-2018-sont-devoilees\/\" \/>\n<meta property=\"og:site_name\" content=\"Fondation de Gasp\u00e9 Beaubien\" \/>\n<meta property=\"article:published_time\" content=\"2018-06-10T19:39:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-01-29T13:38:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.fondationdegaspebeaubien.org\/wp-content\/uploads\/2018\/06\/AquaHacking-Semi-Final-Winners-2018.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"smartbugmedia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"smartbugmedia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.fondationdegaspebeaubien.org\\\/fr\\\/les-cinq-equipes-finalistes-du-defi-aquahacking-2018-sont-devoilees\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fondationdegaspebeaubien.org\\\/fr\\\/les-cinq-equipes-finalistes-du-defi-aquahacking-2018-sont-devoilees\\\/\"},\"author\":{\"name\":\"smartbugmedia\",\"@id\":\"https:\\\/\\\/www.fondationdegaspebeaubien.org\\\/en\\\/#\\\/schema\\\/person\\\/e84c883213d8e6cb00f1775074c74263\"},\"headline\":\"Les cinq \u00e9quipes finalistes du d\u00e9fi Aquahacking 2018 sont d\u00e9voil\u00e9es\",\"datePublished\":\"2018-06-10T19:39:19+00:00\",\"dateModified\":\"2020-01-29T13:38:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.fondationdegaspebeaubien.org\\\/fr\\\/les-cinq-equipes-finalistes-du-defi-aquahacking-2018-sont-devoilees\\\/\"},\"wordCount\":629,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.fondationdegaspebeaubien.org\\\/fr\\\/les-cinq-equipes-finalistes-du-defi-aquahacking-2018-sont-devoilees\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.fondationdegaspebeaubien.org\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/AquaHacking-Semi-Final-Winners-2018.jpg\",\"articleSection\":[\"AquaAction\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.fondationdegaspebeaubien.org\\\/fr\\\/les-cinq-equipes-finalistes-du-defi-aquahacking-2018-sont-devoilees\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.fondationdegaspebeaubien.org\\\/fr\\\/les-cinq-equipes-finalistes-du-defi-aquahacking-2018-sont-devoilees\\\/\",\"url\":\"https:\\\/\\\/www.fondationdegaspebeaubien.org\\\/fr\\\/les-cinq-equipes-finalistes-du-defi-aquahacking-2018-sont-devoilees\\\/\",\"name\":\"Les cinq \u00e9quipes finalistes du d\u00e9fi Aquahacking 2018 sont d\u00e9voil\u00e9es - Fondation de Gasp\u00e9 Beaubien\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fondationdegaspebeaubien.org\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.fondationdegaspebeaubien.org\\\/fr\\\/les-cinq-equipes-finalistes-du-defi-aquahacking-2018-sont-devoilees\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fondationdegaspebeaubien.org\\\/fr\\\/les-cinq-equipes-finalistes-du-defi-aquahacking-2018-sont-devoilees\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.fondationdegaspebeaubien.org\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/AquaHacking-Semi-Final-Winners-2018.jpg\",\"datePublished\":\"2018-06-10T19:39:19+00:00\",\"dateModified\":\"2020-01-29T13:38:50+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.fondationdegaspebeaubien.org\\\/en\\\/#\\\/schema\\\/person\\\/e84c883213d8e6cb00f1775074c74263\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.fondationdegaspebeaubien.org\\\/fr\\\/les-cinq-equipes-finalistes-du-defi-aquahacking-2018-sont-devoilees\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.fondationdegaspebeaubien.org\\\/fr\\\/les-cinq-equipes-finalistes-du-defi-aquahacking-2018-sont-devoilees\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.fondationdegaspebeaubien.org\\\/fr\\\/les-cinq-equipes-finalistes-du-defi-aquahacking-2018-sont-devoilees\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.fondationdegaspebeaubien.org\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/AquaHacking-Semi-Final-Winners-2018.jpg\",\"contentUrl\":\"https:\\\/\\\/www.fondationdegaspebeaubien.org\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/AquaHacking-Semi-Final-Winners-2018.jpg\",\"width\":900,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.fondationdegaspebeaubien.org\\\/fr\\\/les-cinq-equipes-finalistes-du-defi-aquahacking-2018-sont-devoilees\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.fondationdegaspebeaubien.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les cinq \u00e9quipes finalistes du d\u00e9fi Aquahacking 2018 sont d\u00e9voil\u00e9es\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.fondationdegaspebeaubien.org\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.fondationdegaspebeaubien.org\\\/en\\\/\",\"name\":\"Fondation de Gasp\u00e9 Beaubien\",\"description\":\"Appuyer le changement au sein de la communaut\u00e9\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.fondationdegaspebeaubien.org\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.fondationdegaspebeaubien.org\\\/en\\\/#\\\/schema\\\/person\\\/e84c883213d8e6cb00f1775074c74263\",\"name\":\"smartbugmedia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/97b857c2b07334a0c01d0a4c9531e3bbfbced011ed68c984b0e56002a21bde47?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/97b857c2b07334a0c01d0a4c9531e3bbfbced011ed68c984b0e56002a21bde47?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/97b857c2b07334a0c01d0a4c9531e3bbfbced011ed68c984b0e56002a21bde47?s=96&d=mm&r=g\",\"caption\":\"smartbugmedia\"},\"url\":\"https:\\\/\\\/www.fondationdegaspebeaubien.org\\\/fr\\\/author\\\/cms\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les cinq \u00e9quipes finalistes du d\u00e9fi Aquahacking 2018 sont d\u00e9voil\u00e9es - Fondation de Gasp\u00e9 Beaubien","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fondationdegaspebeaubien.org\/fr\/les-cinq-equipes-finalistes-du-defi-aquahacking-2018-sont-devoilees\/","og_locale":"fr_FR","og_type":"article","og_title":"Les cinq \u00e9quipes finalistes du d\u00e9fi Aquahacking 2018 sont d\u00e9voil\u00e9es - Fondation de Gasp\u00e9 Beaubien","og_description":"Toronto, ON, (Dimanche 10 juin 2018) \u2013 Cinq \u00e9quipes ont \u00e9t\u00e9 s\u00e9lectionn\u00e9es comme finalistes de la demi-finale du D\u00e9fi AquaHacking 2018. Au cours des trois derniers mois, certains des jeunes innovateurs les plus brillants de diverses universit\u00e9s du Qu\u00e9bec, de l&rsquo;Ontario et des \u00c9tats-Unis ont form\u00e9 des \u00e9quipes multidisciplinaires pour cr\u00e9er des solutions innovatrices en [&hellip;]","og_url":"https:\/\/www.fondationdegaspebeaubien.org\/fr\/les-cinq-equipes-finalistes-du-defi-aquahacking-2018-sont-devoilees\/","og_site_name":"Fondation de Gasp\u00e9 Beaubien","article_published_time":"2018-06-10T19:39:19+00:00","article_modified_time":"2020-01-29T13:38:50+00:00","og_image":[{"width":900,"height":400,"url":"https:\/\/www.fondationdegaspebeaubien.org\/wp-content\/uploads\/2018\/06\/AquaHacking-Semi-Final-Winners-2018.jpg","type":"image\/jpeg"}],"author":"smartbugmedia","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"smartbugmedia","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fondationdegaspebeaubien.org\/fr\/les-cinq-equipes-finalistes-du-defi-aquahacking-2018-sont-devoilees\/#article","isPartOf":{"@id":"https:\/\/www.fondationdegaspebeaubien.org\/fr\/les-cinq-equipes-finalistes-du-defi-aquahacking-2018-sont-devoilees\/"},"author":{"name":"smartbugmedia","@id":"https:\/\/www.fondationdegaspebeaubien.org\/en\/#\/schema\/person\/e84c883213d8e6cb00f1775074c74263"},"headline":"Les cinq \u00e9quipes finalistes du d\u00e9fi Aquahacking 2018 sont d\u00e9voil\u00e9es","datePublished":"2018-06-10T19:39:19+00:00","dateModified":"2020-01-29T13:38:50+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fondationdegaspebeaubien.org\/fr\/les-cinq-equipes-finalistes-du-defi-aquahacking-2018-sont-devoilees\/"},"wordCount":629,"commentCount":0,"image":{"@id":"https:\/\/www.fondationdegaspebeaubien.org\/fr\/les-cinq-equipes-finalistes-du-defi-aquahacking-2018-sont-devoilees\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fondationdegaspebeaubien.org\/wp-content\/uploads\/2018\/06\/AquaHacking-Semi-Final-Winners-2018.jpg","articleSection":["AquaAction"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.fondationdegaspebeaubien.org\/fr\/les-cinq-equipes-finalistes-du-defi-aquahacking-2018-sont-devoilees\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.fondationdegaspebeaubien.org\/fr\/les-cinq-equipes-finalistes-du-defi-aquahacking-2018-sont-devoilees\/","url":"https:\/\/www.fondationdegaspebeaubien.org\/fr\/les-cinq-equipes-finalistes-du-defi-aquahacking-2018-sont-devoilees\/","name":"Les cinq \u00e9quipes finalistes du d\u00e9fi Aquahacking 2018 sont d\u00e9voil\u00e9es - Fondation de Gasp\u00e9 Beaubien","isPartOf":{"@id":"https:\/\/www.fondationdegaspebeaubien.org\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.fondationdegaspebeaubien.org\/fr\/les-cinq-equipes-finalistes-du-defi-aquahacking-2018-sont-devoilees\/#primaryimage"},"image":{"@id":"https:\/\/www.fondationdegaspebeaubien.org\/fr\/les-cinq-equipes-finalistes-du-defi-aquahacking-2018-sont-devoilees\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fondationdegaspebeaubien.org\/wp-content\/uploads\/2018\/06\/AquaHacking-Semi-Final-Winners-2018.jpg","datePublished":"2018-06-10T19:39:19+00:00","dateModified":"2020-01-29T13:38:50+00:00","author":{"@id":"https:\/\/www.fondationdegaspebeaubien.org\/en\/#\/schema\/person\/e84c883213d8e6cb00f1775074c74263"},"breadcrumb":{"@id":"https:\/\/www.fondationdegaspebeaubien.org\/fr\/les-cinq-equipes-finalistes-du-defi-aquahacking-2018-sont-devoilees\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fondationdegaspebeaubien.org\/fr\/les-cinq-equipes-finalistes-du-defi-aquahacking-2018-sont-devoilees\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.fondationdegaspebeaubien.org\/fr\/les-cinq-equipes-finalistes-du-defi-aquahacking-2018-sont-devoilees\/#primaryimage","url":"https:\/\/www.fondationdegaspebeaubien.org\/wp-content\/uploads\/2018\/06\/AquaHacking-Semi-Final-Winners-2018.jpg","contentUrl":"https:\/\/www.fondationdegaspebeaubien.org\/wp-content\/uploads\/2018\/06\/AquaHacking-Semi-Final-Winners-2018.jpg","width":900,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/www.fondationdegaspebeaubien.org\/fr\/les-cinq-equipes-finalistes-du-defi-aquahacking-2018-sont-devoilees\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.fondationdegaspebeaubien.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Les cinq \u00e9quipes finalistes du d\u00e9fi Aquahacking 2018 sont d\u00e9voil\u00e9es"}]},{"@type":"WebSite","@id":"https:\/\/www.fondationdegaspebeaubien.org\/en\/#website","url":"https:\/\/www.fondationdegaspebeaubien.org\/en\/","name":"Fondation de Gasp\u00e9 Beaubien","description":"Appuyer le changement au sein de la communaut\u00e9","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fondationdegaspebeaubien.org\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.fondationdegaspebeaubien.org\/en\/#\/schema\/person\/e84c883213d8e6cb00f1775074c74263","name":"smartbugmedia","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/97b857c2b07334a0c01d0a4c9531e3bbfbced011ed68c984b0e56002a21bde47?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/97b857c2b07334a0c01d0a4c9531e3bbfbced011ed68c984b0e56002a21bde47?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/97b857c2b07334a0c01d0a4c9531e3bbfbced011ed68c984b0e56002a21bde47?s=96&d=mm&r=g","caption":"smartbugmedia"},"url":"https:\/\/www.fondationdegaspebeaubien.org\/fr\/author\/cms\/"}]}},"_links":{"self":[{"href":"https:\/\/www.fondationdegaspebeaubien.org\/fr\/wp-json\/wp\/v2\/posts\/965","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fondationdegaspebeaubien.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fondationdegaspebeaubien.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fondationdegaspebeaubien.org\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fondationdegaspebeaubien.org\/fr\/wp-json\/wp\/v2\/comments?post=965"}],"version-history":[{"count":2,"href":"https:\/\/www.fondationdegaspebeaubien.org\/fr\/wp-json\/wp\/v2\/posts\/965\/revisions"}],"predecessor-version":[{"id":1136,"href":"https:\/\/www.fondationdegaspebeaubien.org\/fr\/wp-json\/wp\/v2\/posts\/965\/revisions\/1136"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fondationdegaspebeaubien.org\/fr\/wp-json\/wp\/v2\/media\/1077"}],"wp:attachment":[{"href":"https:\/\/www.fondationdegaspebeaubien.org\/fr\/wp-json\/wp\/v2\/media?parent=965"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fondationdegaspebeaubien.org\/fr\/wp-json\/wp\/v2\/categories?post=965"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fondationdegaspebeaubien.org\/fr\/wp-json\/wp\/v2\/tags?post=965"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}